{"id":14767,"date":"2024-08-05T01:00:16","date_gmt":"2024-08-05T05:00:16","guid":{"rendered":"https:\/\/cepreaching.org\/?post_type=commentary&#038;p=14767"},"modified":"2024-08-02T13:07:20","modified_gmt":"2024-08-02T17:07:20","slug":"esdras-4-1-10","status":"publish","type":"commentary","link":"https:\/\/cepreaching.org\/es\/commentary\/leopoldo-cervantes-ortiz\/esdras-4-1-10\/","title":{"rendered":"Esdras 4.1-10"},"content":{"rendered":"<p>Entonces la gente que viv\u00eda all\u00ed trataba de desanimar a los jud\u00edos y meterles miedo para que no reconstruyeran el templo. Adem\u00e1s, les pagaron a algunos asistentes del gobierno para que no los dejaran continuar con la reconstrucci\u00f3n. \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0Esdras 4.4-5a, <em>TLA<\/em><\/p>\n<p><strong>Trasfondo b\u00edblico-teol\u00f3gico<\/strong><\/p>\n<p>El texto de Esdras no deja de registrar la conflictividad causada por la forma tan positiva con que los repatriados de Israel comenzaron los trabajos para reconstruir inicialmente, el altar y el templo de Jerusal\u00e9n. Al transcurrir el tiempo y con el cambio de monarcas persas, la situaci\u00f3n del principio, tan firme y bien determinada por el decreto del rey Ciro II, fue modific\u00e1ndose hasta el punto de que surgi\u00f3 una verdadera oposici\u00f3n a ese proyecto, disfrazada, como bien subraya Esdras 4, de una aparente disposici\u00f3n para apoyarlo. Se habla expl\u00edcitamente de \u201clos enemigos de Jud\u00e1 y de Benjam\u00edn\u201d (v. 1a), quienes se presentaron ante Zorobabel y los jefes de las familias en un di\u00e1logo imposible. Se trataba de una poblaci\u00f3n extranjera (pagana) que hab\u00eda sido llevada a Palestina por Esar-had\u00f3n rey de Asiria entre los a\u00f1os 681 y 669 a.C., hijo de Senaquerib. En esa \u201ctransmigraci\u00f3n\u201d forzada vio II Reyes 17.24-41 el origen de los samaritanos y de la implantaci\u00f3n de cultos diferentes al yahvismo. De manera que se conjuntaron elementos raciales, religiosos y pol\u00edticos para originar esta oposici\u00f3n que posteriormente dar\u00eda frutos: \u201cA esta primera oposici\u00f3n se a\u00f1ade otra: si los primeros apelan por dos veces a un soberano extranjero movido por el esp\u00edritu de Yahv\u00e9, que los ha hecho volver a su tierra, Ciro (3.7 y 4.3), los segundos est\u00e1n vinculados con el terrible soberano pagano Asarad\u00f3n, rey de Asur, que los hab\u00eda deportado a una tierra que les segu\u00eda resultando extra\u00f1a (4.2)\u201d (P. Abadie).<\/p>\n<p><strong>La oposici\u00f3n enemiga<\/strong><\/p>\n<p>La tem\u00e1tica planteada anticipa el resto de la narraci\u00f3n: la menci\u00f3n de los \u201cenemigos\u201d en Esd 4.1 se repite en Neh 4.5, y el intento de hacer que fracase el proyecto de los deportados (Esd 4.5) tiene su correspondiente inverso en Neh 4.15: \u201cY cuando oyeron nuestros enemigos que lo hab\u00edamos entendido, y que Dios hab\u00eda desbaratado el consejo de ellos, nos volvimos todos al muro, cada uno a su tarea\u201d. As\u00ed, desde el principio el lector est\u00e1 informado: \u201cel fracaso ser\u00e1 tan s\u00f3lo aparente y Dios dar\u00e1 la vuelta a la situaci\u00f3n en favor de su pueblo\u201d (<em>\u00cddem<\/em>). Los vv. 1-3 asimilan de manera pol\u00e9mica a los \u201cenemigos de Jud\u00e1 y Benjam\u00edn\u201d con las poblaciones extranjeras (\u201clos pueblos de los pa\u00edses\u201d) deportadas por los soberanos asirios. \u201cSi la expresi\u00f3n es muy imprecisa, crea, no obstante, una tensi\u00f3n entre estos aut\u00f3ctonos extranjeros del pa\u00eds y \u2018los hijos de la deportaci\u00f3n\u2019, es decir, los repatriados dirigidos por Josu\u00e9 y Zorobabel\u201d (P. Abadie y P. de Martin de Vivi\u00e8s).<\/p>\n<p>La argumentaci\u00f3n del v. 2 oculta, en buena parte, la mezcla de creencias y pr\u00e1cticas descritas en II Reyes 17, presentada con el tono antipagano del momento: no necesariamente era verdad que esos grupos hubieran aceptado el yahvismo como creencia religiosa principal. La respuesta de Zorobabel y los dem\u00e1s l\u00edderes es directa y en\u00e9rgica: solamente los jud\u00edos (factor racial y religioso) pod\u00edan llevar a cabo las obras, debido a la orden de Ciro (v. 3). La reacci\u00f3n esperada, la manifestaci\u00f3n abierta de la oposici\u00f3n al trabajo aparece inmediatamente (v. 4), con lo que se intent\u00f3 desanimar a los reconstructores. Estamos ante una \u201cuna visi\u00f3n puramente teol\u00f3gica, centrada en una definici\u00f3n estricta de la identidad jud\u00eda. Queda por identificar a estos \u2018pueblos que habitan el pa\u00eds\u2019 [\u2026]. Sin duda, m\u00e1s que referirse a los extranjeros en el pa\u00eds, apunta a los jud\u00edos no deportados que se mostraban reacios a las reivindicaciones de los antiguos propietarios para que les devolvieran sus tierras; algunos or\u00e1culos prof\u00e9ticos (Ez 11.14-21; 33.23-29) van en este sentido\u201d (<em>\u00cddem<\/em>).<\/p>\n<p><strong>Sobornos e intrigas contra el proyecto de reconstrucci\u00f3n<\/strong><\/p>\n<p>Las acciones descritas en el v. 5 muestran la forma desleal (sobornos e intrigas) con que se busc\u00f3 detener el proyecto de reconstrucci\u00f3n durante el reinado de Ciro y Dar\u00edo. Pero la labor de zapa y rechazo no termin\u00f3 ah\u00ed: ya en el reinado de Asuero (Jerjes I, 519-465 a.C.), hijo de Dar\u00edo, presentaron una acusaci\u00f3n contra los jud\u00edos (v. 6) y, mediante una argumentaci\u00f3n estrictamente pol\u00edtica, se dirigieron despu\u00e9s a Artajerjes (465-424 a.C.) para denunciarlos tambi\u00e9n. Aqu\u00ed aparecen los nombres de los dirigentes antijud\u00edos, autoridades persas locales y sus esbirros (vv. 7-10). M\u00e1s all\u00e1 de la precisi\u00f3n cronol\u00f3gica, la carta, escrita en arameo y traducida al persa es una acusaci\u00f3n frontal que se\u00f1ala el car\u00e1cter \u201crebelde\u201d de la ciudad (12b, 15b: antecedente para su destrucci\u00f3n) y el enorme riesgo posterior que implicar\u00eda su reconstrucci\u00f3n: \u201c<strong><sup>\u00a0<\/sup><\/strong>Tambi\u00e9n le hacemos saber que cuando ellos terminen de reparar esos muros y la ciudad est\u00e9 reconstruida, no van a querer pagar ninguna clase de impuestos, y el tesoro del reino sufrir\u00e1 p\u00e9rdidas\u201d (v. 13). Pero lo cierto es que entraban muchos factores en juego:<\/p>\n<p style=\"padding-left: 80px;\">El texto dramatiza esta realidad, evocando un prolongado conflicto que termina con una interrupci\u00f3n de los trabajos \u201chasta el segundo a\u00f1o del reinado de Dar\u00edo, rey de Persia\u201d (4,24), en alg\u00fan momento entre el 537 y el 520 a.C. En realidad, exist\u00edan otros factores que explican las dificultades para la reconstrucci\u00f3n del Templo, algunos de tipo econ\u00f3mico (Hag 1.5-11: 2.16-19; Zac 8.10), otros debidos a disensiones internas (Is 58.4), e incluso tal vez la presencia de movimientos hostiles a esta obra (Is 66.1-2). La reconstrucci\u00f3n de los hechos en Esdras enmascara estos diversos factores a favor de una imagen altamente apolog\u00e9tica (<em>\u00cddem<\/em>).<\/p>\n<p>La menci\u00f3n de las murallas manifiesta la preocupaci\u00f3n pol\u00edtico-econ\u00f3mica de fondo en la carta que resalta con la advertencia final, en t\u00e9rminos de la integridad del imperio en esa zona geogr\u00e1fica: \u201cQueremos que Su Majestad sepa que, si se reconstruye esa ciudad y se terminan de reparar sus muros, usted ya no tendr\u00e1 dominio sobre la provincia que est\u00e1 al oeste del r\u00edo \u00c9ufrates\u201d (v. 16). La misiva tuvo \u00e9xito y la respuesta del rey fue afirmativa para los intereses de los enemigos: orden\u00f3 detener la construcci\u00f3n (21) a fin de \u201cno perjudicar m\u00e1s al reino\u201d (22). La oposici\u00f3n se impuso provisionalmente, \u201ccon poder y violencia\u201d (23) hasta el segundo a\u00f1o de Dar\u00edo (24). La lectura teol\u00f3gica del pasado de Jerusal\u00e9n (\u00a1practicada tambi\u00e9n por sus adversarios!) se volvi\u00f3 en su contra al momento de tomar la determinaci\u00f3n de detener las obras. Po ello, la actitud de aceptaci\u00f3n de ese nuevo obst\u00e1culo deb\u00eda pasar por un reconocimiento y un discernimiento espiritual de los jud\u00edos de las nuevas adversidades que deb\u00edan enfrentar para llevar a cabo los proyectos de Dios en esos tiempos. La estrategia deb\u00eda ser eminentemente religiosa para sobrellevar la oposici\u00f3n y recuperar el \u00e1nimo para seguir colaborando en los planes divinos.<\/p>\n<p><strong>Conclusi\u00f3n<\/strong><\/p>\n<p>Tal como resume Walter Brueggemann al hacer menci\u00f3n del horizonte espiritual de toda esta reconstrucci\u00f3n: \u201cA Israel le quedaba planear y reconstruir la nueva vida que Yahv\u00e9 le hab\u00eda concedido gracias a su perd\u00f3n. Esta planificaci\u00f3n y reconstrucci\u00f3n se convierte en la tarea permanente del juda\u00edsmo. Es obvio que la labor del juda\u00edsmo siempre tiene lugar despu\u00e9s del exilio y se sit\u00faa en el horizonte de la tendencia congregadora, sanadora, reconciliadora y amorosa de Yahv\u00e9\u201d. Cada vez que el pueblo de Dios emprende proyectos importantes de reconstrucci\u00f3n enfrentar\u00e1 oposici\u00f3n y rechazo. Y en cada ocasi\u00f3n deber\u00e1 buscar la conducci\u00f3n divina a fin de orientar y reorientar continuamente sus planes y acciones. Si el \u00e1nimo decae, es preciso atender historias como la de Esdras, quien no cej\u00f3 en su empe\u00f1o por unificar las labores de la comunidad, para lograr as\u00ed la unidad en la fe y en los actos concretos de trabajo y misi\u00f3n.<\/p>\n<p><strong>Sugerencias de lectura<\/strong><\/p>\n<ul>\n<li>Philippe Abadie, <em>El libro de Esdras y de Nehem\u00edas. <\/em>Estella, Verbo Divino, 1998 (Cuadernos b\u00edblicos, 95), <a href=\"http:\/\/www.mercaba.org\/SANLUIS\/CUADERNOS_BIBLICOS\/095%20El%20libro%20de%20Esdras%20y%20de%20Nehemias%20(PHILIPPE%20ABADIE).pdf\">link<\/a>.<\/li>\n<li>Philippe Abadie y Pierre de Martin de Vivi\u00e8s, <em>Los<\/em> <em>cuatro libros de Esdras<\/em>. Estella, Verbo Divino, 2014 (Cuadernos b\u00edblicos, 180)<\/li>\n<li>Walter Brueggemann, <em>Teolog\u00eda del Antiguo Testamento. Un juicio a Yahv\u00e9 Testimonio. <\/em><em> Defensa<\/em><em>.<\/em> Salamanca, S\u00edgueme, 2007 (Biblioteca de estudios b\u00edblicos, 121).<\/li>\n<\/ul>\n","protected":false},"author":4,"featured_media":0,"template":"","categories":[1],"rcl_weeks":[],"authors":[4146],"biblical_books":[4825],"class_list":["post-14767","commentary","type-commentary","status-publish","hentry","category-uncategorized","authors-leopoldo-cervantes-ortiz","biblical_books-esdras-4"],"acf":{"biblical_books":[4825],"type":"non-rcl","legacy_slug":"","legacy_id":"","author":4146,"keywords":"","rcl_week":false,"sunday_name":"","year":"B","date":"20240805","lectionary":"gospel","description":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Esdras 4.1-10 - Center for Excellence in Preaching<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cepreaching.org\/es\/commentary\/leopoldo-cervantes-ortiz\/esdras-4-1-10\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Esdras 4.1-10 - Center for Excellence in Preaching\" \/>\n<meta property=\"og:description\" content=\"Entonces la gente que viv\u00eda all\u00ed trataba de desanimar a los jud\u00edos y meterles miedo para que no reconstruyeran el templo. Adem\u00e1s, les pagaron a algunos asistentes del gobierno para que no los dejaran continuar con la reconstrucci\u00f3n. \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0Esdras 4.4-5a, TLA Trasfondo b\u00edblico-teol\u00f3gico El texto de Esdras no deja de registrar la conflictividad&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cepreaching.org\/es\/commentary\/leopoldo-cervantes-ortiz\/esdras-4-1-10\/\" \/>\n<meta property=\"og:site_name\" content=\"Center for Excellence in Preaching\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cepreaching\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@calvinseminary\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cepreaching.org\/es\/commentary\/leopoldo-cervantes-ortiz\/esdras-4-1-10\/\",\"url\":\"https:\/\/cepreaching.org\/es\/commentary\/leopoldo-cervantes-ortiz\/esdras-4-1-10\/\",\"name\":\"Esdras 4.1-10 - Center for Excellence in Preaching\",\"isPartOf\":{\"@id\":\"https:\/\/cepreaching.org\/es\/#website\"},\"datePublished\":\"2024-08-05T05:00:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/cepreaching.org\/es\/commentary\/leopoldo-cervantes-ortiz\/esdras-4-1-10\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cepreaching.org\/es\/commentary\/leopoldo-cervantes-ortiz\/esdras-4-1-10\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cepreaching.org\/es\/commentary\/leopoldo-cervantes-ortiz\/esdras-4-1-10\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/cepreaching.org\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Esdras 4.1-10\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cepreaching.org\/es\/#website\",\"url\":\"https:\/\/cepreaching.org\/es\/\",\"name\":\"Center for Excellence in Preaching\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/cepreaching.org\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cepreaching.org\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cepreaching.org\/es\/#organization\",\"name\":\"Center for Excellence in Preaching\",\"url\":\"https:\/\/cepreaching.org\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/cepreaching.org\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cepreaching.org\/wp-content\/uploads\/2021\/08\/ceplogo.png\",\"contentUrl\":\"https:\/\/cepreaching.org\/wp-content\/uploads\/2021\/08\/ceplogo.png\",\"width\":100,\"height\":100,\"caption\":\"Center for Excellence in Preaching\"},\"image\":{\"@id\":\"https:\/\/cepreaching.org\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/cepreaching\",\"https:\/\/x.com\/calvinseminary\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Esdras 4.1-10 - Center for Excellence in Preaching","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cepreaching.org\/es\/commentary\/leopoldo-cervantes-ortiz\/esdras-4-1-10\/","og_locale":"es_ES","og_type":"article","og_title":"Esdras 4.1-10 - Center for Excellence in Preaching","og_description":"Entonces la gente que viv\u00eda all\u00ed trataba de desanimar a los jud\u00edos y meterles miedo para que no reconstruyeran el templo. Adem\u00e1s, les pagaron a algunos asistentes del gobierno para que no los dejaran continuar con la reconstrucci\u00f3n. \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0Esdras 4.4-5a, TLA Trasfondo b\u00edblico-teol\u00f3gico El texto de Esdras no deja de registrar la conflictividad&hellip;","og_url":"https:\/\/cepreaching.org\/es\/commentary\/leopoldo-cervantes-ortiz\/esdras-4-1-10\/","og_site_name":"Center for Excellence in Preaching","article_publisher":"https:\/\/www.facebook.com\/cepreaching","twitter_card":"summary_large_image","twitter_site":"@calvinseminary","twitter_misc":{"Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cepreaching.org\/es\/commentary\/leopoldo-cervantes-ortiz\/esdras-4-1-10\/","url":"https:\/\/cepreaching.org\/es\/commentary\/leopoldo-cervantes-ortiz\/esdras-4-1-10\/","name":"Esdras 4.1-10 - Center for Excellence in Preaching","isPartOf":{"@id":"https:\/\/cepreaching.org\/es\/#website"},"datePublished":"2024-08-05T05:00:16+00:00","breadcrumb":{"@id":"https:\/\/cepreaching.org\/es\/commentary\/leopoldo-cervantes-ortiz\/esdras-4-1-10\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cepreaching.org\/es\/commentary\/leopoldo-cervantes-ortiz\/esdras-4-1-10\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cepreaching.org\/es\/commentary\/leopoldo-cervantes-ortiz\/esdras-4-1-10\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cepreaching.org\/es\/"},{"@type":"ListItem","position":2,"name":"Esdras 4.1-10"}]},{"@type":"WebSite","@id":"https:\/\/cepreaching.org\/es\/#website","url":"https:\/\/cepreaching.org\/es\/","name":"Center for Excellence in Preaching","description":"","publisher":{"@id":"https:\/\/cepreaching.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cepreaching.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cepreaching.org\/es\/#organization","name":"Center for Excellence in Preaching","url":"https:\/\/cepreaching.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cepreaching.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/cepreaching.org\/wp-content\/uploads\/2021\/08\/ceplogo.png","contentUrl":"https:\/\/cepreaching.org\/wp-content\/uploads\/2021\/08\/ceplogo.png","width":100,"height":100,"caption":"Center for Excellence in Preaching"},"image":{"@id":"https:\/\/cepreaching.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cepreaching","https:\/\/x.com\/calvinseminary"]}]}},"_links":{"self":[{"href":"https:\/\/cepreaching.org\/es\/wp-json\/wp\/v2\/commentary\/14767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cepreaching.org\/es\/wp-json\/wp\/v2\/commentary"}],"about":[{"href":"https:\/\/cepreaching.org\/es\/wp-json\/wp\/v2\/types\/commentary"}],"author":[{"embeddable":true,"href":"https:\/\/cepreaching.org\/es\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":0,"href":"https:\/\/cepreaching.org\/es\/wp-json\/wp\/v2\/commentary\/14767\/revisions"}],"acf:term":[{"embeddable":true,"taxonomy":"authors","href":"https:\/\/cepreaching.org\/es\/wp-json\/wp\/v2\/authors\/4146"},{"embeddable":true,"taxonomy":"biblical_books","href":"https:\/\/cepreaching.org\/es\/wp-json\/wp\/v2\/biblical_books\/4825"}],"wp:attachment":[{"href":"https:\/\/cepreaching.org\/es\/wp-json\/wp\/v2\/media?parent=14767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cepreaching.org\/es\/wp-json\/wp\/v2\/categories?post=14767"},{"taxonomy":"rcl_weeks","embeddable":true,"href":"https:\/\/cepreaching.org\/es\/wp-json\/wp\/v2\/rcl_weeks?post=14767"},{"taxonomy":"authors","embeddable":true,"href":"https:\/\/cepreaching.org\/es\/wp-json\/wp\/v2\/authors?post=14767"},{"taxonomy":"biblical_books","embeddable":true,"href":"https:\/\/cepreaching.org\/es\/wp-json\/wp\/v2\/biblical_books?post=14767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}